{"id":10364,"date":"2021-05-05T22:00:33","date_gmt":"2021-05-05T20:00:33","guid":{"rendered":"https:\/\/makadama.es\/producto\/olea-colar\/"},"modified":"2024-11-26T07:12:27","modified_gmt":"2024-11-26T06:12:27","slug":"olea-colar","status":"publish","type":"product","link":"https:\/\/makadama.es\/pt-pt\/producto\/olea-colar\/","title":{"rendered":"Olea: Colar"},"content":{"rendered":"<p>O sil\u00eancio da oliveira n\u00e3o \u00e9 assim, pois ela canta-nos com o vento e d\u00e1-nos os seus frutos.<\/p>\n<ul>\n<li>Pe\u00e7a inteiramente fabricada em Espanha.<\/li>\n<li>As j\u00f3ias s\u00e3o feitas \u00e0 m\u00e3o individualmente, pelo que podem apresentar ligeiras diferen\u00e7as.<\/li>\n<li>Desenho pr\u00f3prio: Aleix Guill\u00e9n.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Colar extra longo. Design de j\u00f3ias inspirado na folha de oliveira. Fecho de mosquet\u00e3o e extens\u00e3o.<\/p>\n","protected":false},"featured_media":9352,"template":"","meta":[],"product_brand":[],"product_cat":[144],"product_tag":[],"class_list":["post-10364","product","type-product","status-publish","has-post-thumbnail","product_cat-olea-pt-pt","pa_tipo-collares-pt-pt","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Olea: Colar - Maka Dama<\/title>\n<meta name=\"description\" content=\"Colar extra longo. Design de j\u00f3ias inspirado na folha de oliveira. Fecho de mosquet\u00e3o e extens\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/makadama.es\/pt-pt\/producto\/olea-colar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Olea: Colar - Maka Dama\" \/>\n<meta property=\"og:description\" content=\"Colar extra longo. Design de j\u00f3ias inspirado na folha de oliveira. Fecho de mosquet\u00e3o e extens\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/makadama.es\/pt-pt\/producto\/olea-colar\/\" \/>\n<meta property=\"og:site_name\" content=\"Maka Dama\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-26T06:12:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/makadama.es\/wp-content\/uploads\/2021\/05\/oleco08-_-destacada-min_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/producto\\\/olea-colar\\\/\",\"url\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/producto\\\/olea-colar\\\/\",\"name\":\"Olea: Colar - Maka Dama\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/producto\\\/olea-colar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/producto\\\/olea-colar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/makadama.es\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/oleco08-_-destacada-min_.jpg\",\"datePublished\":\"2021-05-05T20:00:33+00:00\",\"dateModified\":\"2024-11-26T06:12:27+00:00\",\"description\":\"Colar extra longo. Design de j\u00f3ias inspirado na folha de oliveira. Fecho de mosquet\u00e3o e extens\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/producto\\\/olea-colar\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/producto\\\/olea-colar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/producto\\\/olea-colar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/makadama.es\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/oleco08-_-destacada-min_.jpg\",\"contentUrl\":\"https:\\\/\\\/makadama.es\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/oleco08-_-destacada-min_.jpg\",\"width\":960,\"height\":960,\"caption\":\"Olea Colar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/producto\\\/olea-colar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/tienda-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Olea: Colar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/\",\"name\":\"Maka Dama\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/#organization\",\"name\":\"Maka Dama\",\"url\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/makadama.es\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-logo-2.png\",\"contentUrl\":\"https:\\\/\\\/makadama.es\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-logo-2.png\",\"width\":250,\"height\":47,\"caption\":\"Maka Dama\"},\"image\":{\"@id\":\"https:\\\/\\\/makadama.es\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Olea: Colar - Maka Dama","description":"Colar extra longo. Design de j\u00f3ias inspirado na folha de oliveira. Fecho de mosquet\u00e3o e extens\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/makadama.es\/pt-pt\/producto\/olea-colar\/","og_locale":"pt_PT","og_type":"article","og_title":"Olea: Colar - Maka Dama","og_description":"Colar extra longo. Design de j\u00f3ias inspirado na folha de oliveira. Fecho de mosquet\u00e3o e extens\u00e3o.","og_url":"https:\/\/makadama.es\/pt-pt\/producto\/olea-colar\/","og_site_name":"Maka Dama","article_modified_time":"2024-11-26T06:12:27+00:00","og_image":[{"width":960,"height":960,"url":"https:\/\/makadama.es\/wp-content\/uploads\/2021\/05\/oleco08-_-destacada-min_.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/makadama.es\/pt-pt\/producto\/olea-colar\/","url":"https:\/\/makadama.es\/pt-pt\/producto\/olea-colar\/","name":"Olea: Colar - Maka Dama","isPartOf":{"@id":"https:\/\/makadama.es\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/makadama.es\/pt-pt\/producto\/olea-colar\/#primaryimage"},"image":{"@id":"https:\/\/makadama.es\/pt-pt\/producto\/olea-colar\/#primaryimage"},"thumbnailUrl":"https:\/\/makadama.es\/wp-content\/uploads\/2021\/05\/oleco08-_-destacada-min_.jpg","datePublished":"2021-05-05T20:00:33+00:00","dateModified":"2024-11-26T06:12:27+00:00","description":"Colar extra longo. Design de j\u00f3ias inspirado na folha de oliveira. Fecho de mosquet\u00e3o e extens\u00e3o.","breadcrumb":{"@id":"https:\/\/makadama.es\/pt-pt\/producto\/olea-colar\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/makadama.es\/pt-pt\/producto\/olea-colar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/makadama.es\/pt-pt\/producto\/olea-colar\/#primaryimage","url":"https:\/\/makadama.es\/wp-content\/uploads\/2021\/05\/oleco08-_-destacada-min_.jpg","contentUrl":"https:\/\/makadama.es\/wp-content\/uploads\/2021\/05\/oleco08-_-destacada-min_.jpg","width":960,"height":960,"caption":"Olea Colar"},{"@type":"BreadcrumbList","@id":"https:\/\/makadama.es\/pt-pt\/producto\/olea-colar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/makadama.es\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/makadama.es\/pt-pt\/tienda-2\/"},{"@type":"ListItem","position":3,"name":"Olea: Colar"}]},{"@type":"WebSite","@id":"https:\/\/makadama.es\/pt-pt\/#website","url":"https:\/\/makadama.es\/pt-pt\/","name":"Maka Dama","description":"","publisher":{"@id":"https:\/\/makadama.es\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/makadama.es\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/makadama.es\/pt-pt\/#organization","name":"Maka Dama","url":"https:\/\/makadama.es\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/makadama.es\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/makadama.es\/wp-content\/uploads\/2023\/08\/cropped-logo-2.png","contentUrl":"https:\/\/makadama.es\/wp-content\/uploads\/2023\/08\/cropped-logo-2.png","width":250,"height":47,"caption":"Maka Dama"},"image":{"@id":"https:\/\/makadama.es\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/makadama.es\/pt-pt\/wp-json\/wp\/v2\/product\/10364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/makadama.es\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/makadama.es\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/makadama.es\/pt-pt\/wp-json\/wp\/v2\/media\/9352"}],"wp:attachment":[{"href":"https:\/\/makadama.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=10364"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/makadama.es\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=10364"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/makadama.es\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=10364"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/makadama.es\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=10364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}